{"id":15646,"date":"2025-11-03T13:35:02","date_gmt":"2025-11-03T16:35:02","guid":{"rendered":"https:\/\/jornalismo.ufsj.edu.br\/van\/?p=15646"},"modified":"2025-11-05T14:48:09","modified_gmt":"2025-11-05T17:48:09","slug":"basta","status":"publish","type":"post","link":"http:\/\/jornalismo.ufsj.edu.br\/van\/basta\/","title":{"rendered":"Basta!"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>Por Ana Cl\u00e1udia Almeida<\/strong><\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"http:\/\/jornalismo.ufsj.edu.br\/van\/wp-content\/uploads\/2025\/11\/IMG_5513-819x1024.jpeg\" alt=\"\" class=\"wp-image-15648\" style=\"width:414px;height:auto\" srcset=\"http:\/\/jornalismo.ufsj.edu.br\/van\/wp-content\/uploads\/2025\/11\/IMG_5513-819x1024.jpeg 819w, http:\/\/jornalismo.ufsj.edu.br\/van\/wp-content\/uploads\/2025\/11\/IMG_5513-240x300.jpeg 240w, http:\/\/jornalismo.ufsj.edu.br\/van\/wp-content\/uploads\/2025\/11\/IMG_5513-768x960.jpeg 768w, http:\/\/jornalismo.ufsj.edu.br\/van\/wp-content\/uploads\/2025\/11\/IMG_5513-1229x1536.jpeg 1229w, http:\/\/jornalismo.ufsj.edu.br\/van\/wp-content\/uploads\/2025\/11\/IMG_5513-1638x2048.jpeg 1638w, http:\/\/jornalismo.ufsj.edu.br\/van\/wp-content\/uploads\/2025\/11\/IMG_5513-scaled.jpeg 2048w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Personalidades negras que marcaram a luta pela equidade racial no Brasil. Fotos: Google Imagens. Arte: Ana Cl\u00e1udia Almeida<\/figcaption><\/figure>\n<\/div>\n\n\n<p>H\u00e1 cerca de quinze anos, um decreto se tornou mais um marco hist\u00f3rico brasileiro. Um posicionamento antirracista, enfim consolidado, fez surgir um vislumbre de esperan\u00e7a. Oficializado como o Dia da Consci\u00eancia Negra em 2011, 20 de novembro prometeu nunca mais ser o mesmo, por\u00e9m muitas vezes se esquece.<\/p>\n\n\n\n<p>Dia Nacional de Zumbi, agora feriado nacional, n\u00e3o merece ser aclamado em apenas 24 horas. Tamb\u00e9m n\u00e3o apenas em novembro, mas convenhamos ser um come\u00e7o. Come\u00e7o? Em 2025? Pois \u00e9, caro leitor, estamos sempre atrasados.&nbsp;<\/p>\n\n\n\n<p>Brasil, \u00faltimo pa\u00eds das Am\u00e9ricas a abolir a escravid\u00e3o e um sistema constru\u00eddo com viol\u00eancia e condi\u00e7\u00f5es de trabalho desumanas. Brasil, Rep\u00fablica Federativa e amn\u00e9sia nacional. \u201c137 anos de continuidade e radicaliza\u00e7\u00e3o do racismo estrutural&#8221;, para a historiadora Lilia Schwarcz. \u201cDemocracia racial, um mito de domina\u00e7\u00e3o\u201d, para a pesquisadora L\u00e9lia Gonzalez.<\/p>\n\n\n\n<p>Para uma sociedade onde o racismo \u00e9 ainda um \u201csintoma da neurose da cultura brasileira\u201d, a resist\u00eancia ancestral de indiv\u00edduos escravizados s\u00e3o reduzidos a nada. A forma\u00e7\u00e3o de quilombos, de revoltas, de lideran\u00e7as engajadas desde Dandara, passando por Lu\u00eds Gama, at\u00e9 Carolina Maria de Jesus\u2026reduzidos a nada.<\/p>\n\n\n\n<p>Basta! N\u00e3o basta esquecer em 364 dias e, com discursos decorados, celebrar a data comemorativa. Basta! N\u00e3o basta apenas eventos culturais, sem financiar mudan\u00e7as estruturais. Basta! N\u00e3o basta n\u00e3o ser racista, \u00e9 preciso ser antirracista&#8221;.<\/p>\n\n\n\n<p>Contra um legado centen\u00e1rio de oculta\u00e7\u00e3o e desigualdade racial, armados de reflex\u00f5es e a\u00e7\u00f5es. Mais pol\u00edticas p\u00fablicas assertivas e razo\u00e1veis, mais equidade. Mais re(conhecimento), mais liberdade.&nbsp;<\/p>\n\n\n\n<p>Em tempos dos finados Abdias do Nascimento e Marielle Franco, de Concei\u00e7\u00e3o Evaristo e Djamilla Ribeiro, a dedica\u00e7\u00e3o antirracista precisa ser geral. A exalta\u00e7\u00e3o da mem\u00f3ria e o aprendizado com a hist\u00f3ria surgem como caminhos de mais dignidade ao povo negro. Basta! Como o alagoano de Palmares disse: \u201c\u00c9 chegada a hora de tirar nossa na\u00e7\u00e3o das trevas da injusti\u00e7a racial!\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00f4nica &#8211; H\u00e1 cerca de quinze anos, um decreto se tornou mais um marco hist\u00f3rico brasileiro. Um posicionamento antirracista, enfim consolidado, fez surgir um vislumbre de esperan\u00e7a. Oficializado como o Dia da Consci\u00eancia Negra em 2011, 20 de novembro prometeu nunca mais ser o mesmo, por\u00e9m muitas vezes se esquece.<\/p>\n","protected":false},"author":2,"featured_media":15648,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_themeisle_gutenberg_block_has_review":false,"cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[696,728,10,13,1],"tags":[149,152,14],"class_list":["post-15646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidadania","category-consciencia-negra","category-cronica","category-cultura","category-sem-categoria","tag-cidades","tag-cultura","tag-sao-joao-del-rei"],"_links":{"self":[{"href":"http:\/\/jornalismo.ufsj.edu.br\/van\/wp-json\/wp\/v2\/posts\/15646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/jornalismo.ufsj.edu.br\/van\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/jornalismo.ufsj.edu.br\/van\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/jornalismo.ufsj.edu.br\/van\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/jornalismo.ufsj.edu.br\/van\/wp-json\/wp\/v2\/comments?post=15646"}],"version-history":[{"count":3,"href":"http:\/\/jornalismo.ufsj.edu.br\/van\/wp-json\/wp\/v2\/posts\/15646\/revisions"}],"predecessor-version":[{"id":15651,"href":"http:\/\/jornalismo.ufsj.edu.br\/van\/wp-json\/wp\/v2\/posts\/15646\/revisions\/15651"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/jornalismo.ufsj.edu.br\/van\/wp-json\/wp\/v2\/media\/15648"}],"wp:attachment":[{"href":"http:\/\/jornalismo.ufsj.edu.br\/van\/wp-json\/wp\/v2\/media?parent=15646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/jornalismo.ufsj.edu.br\/van\/wp-json\/wp\/v2\/categories?post=15646"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/jornalismo.ufsj.edu.br\/van\/wp-json\/wp\/v2\/tags?post=15646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}